{"id":1633,"date":"2024-02-05T03:47:58","date_gmt":"2024-02-05T03:47:58","guid":{"rendered":"https:\/\/cividesk.com\/?p=1633"},"modified":"2024-02-05T04:13:33","modified_gmt":"2024-02-05T04:13:33","slug":"civicrm-at-the-museum","status":"publish","type":"post","link":"https:\/\/cividesk.com\/fr\/civicrm-at-the-museum\/","title":{"rendered":"CiviCRM au Mus\u00e9e"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1633\" class=\"elementor elementor-1633\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b157c9 e-flex e-con-boxed e-con e-parent\" data-id=\"9b157c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-387fd4d elementor-widget elementor-widget-text-editor\" data-id=\"387fd4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le Mus\u00e9e d&#039;Art et d&#039;Histoire du Juda\u00efsme (mahJ) est le plus grand mus\u00e9e fran\u00e7ais d&#039;art et d&#039;histoire juive. Situ\u00e9e dans le quartier du Marais \u00e0 Paris, en France, la collection permanente du mus\u00e9e pr\u00e9sente 700 \u0153uvres d&#039;art et objets sur les 12 000 objets de sa collection, qui repr\u00e9sentent l&#039;histoire des communaut\u00e9s juives d&#039;Europe et de M\u00e9diterran\u00e9e du Moyen \u00c2ge \u00e0 nos jours. Le mus\u00e9e accueille de nombreuses manifestations culturelles, propose des services \u00e9ducatifs aux enfants et aux familles, propose aux visiteurs une vaste m\u00e9diath\u00e8que et une librairie de plus de 5 000 titres.<\/p><p>Cividesk s&#039;est r\u00e9cemment entretenu avec le responsable informatique du mus\u00e9e, S\u00e9bastien Pauly, et l&#039;attach\u00e9e aux communications, Louise Tellier, pour en savoir plus sur les d\u00e9fis auxquels ils ont \u00e9t\u00e9 confront\u00e9s avant de passer \u00e0 CiviCRM, les raisons pour lesquelles ils avaient besoin de faire un changement, leurs exp\u00e9riences de transition vers CiviCRM et les avantages de l&#039;utilisation de ce cloud. base de donn\u00e9es bas\u00e9e.<\/p><p><strong>Avant CiviCRM :<\/strong><br \/>Le mus\u00e9e a stock\u00e9 ses contacts dans une base de donn\u00e9es FileMaker, mais a \u00e9t\u00e9 confront\u00e9 \u00e0 plusieurs limitations majeures de la base de donn\u00e9es, notamment l&#039;impossibilit\u00e9 pour tous les membres du personnel d&#039;utiliser le programme en m\u00eame temps. Deuxi\u00e8mement, ils utilisaient plusieurs copies de FileMaker et aucune possibilit\u00e9 de synchroniser les diff\u00e9rentes versions. Il y avait \u00e9galement de nombreuses incoh\u00e9rences au sein des installations concernant la normalisation, notamment les majuscules et les accents des noms propres. Leur besoin de mieux g\u00e9rer les dons, les adh\u00e9sions et la billetterie des visiteurs du mus\u00e9e (tout cela n&#039;est pas possible dans FileMaker) \u00e9tait une raison suppl\u00e9mentaire pour identifier une solution qui leur permettrait de g\u00e9rer plus efficacement les op\u00e9rations quotidiennes du mus\u00e9e.<br \/>Dans le m\u00eame temps, ils avaient \u00e9galement besoin d&#039;un tout nouveau site Web et ont d\u00e9cid\u00e9 d&#039;utiliser le CMS open source Drupal comme technologie pour le d\u00e9veloppement du site. L&#039;agence Drupal charg\u00e9e de d\u00e9velopper le nouveau site a sugg\u00e9r\u00e9 d&#039;utiliser CiviCRM comme base de donn\u00e9es, car elle est \u00e9galement open source et s&#039;int\u00e8gre tr\u00e8s bien \u00e0 Drupal. Ils ont recommand\u00e9 de travailler avec Cividesk en raison de leur expertise en CiviCRM et de leur personnel francophone. Le mus\u00e9e a d\u00e9cid\u00e9<br \/>CiviCRM \u00e9tait un bon choix car il est bas\u00e9 sur le Web et peut donc \u00eatre consult\u00e9 par tout le personnel, g\u00e9rer les dons et les adh\u00e9sions et \u00eatre int\u00e9gr\u00e9 \u00e0 leur syst\u00e8me de billetterie. Ils ont \u00e9galement d\u00e9cid\u00e9 de travailler avec Cividesk non seulement pour la configuration et la mise en \u0153uvre de CiviCRM, mais \u00e9galement pour leurs services d&#039;assistance mensuels tels que l&#039;assistance continue, le mentorat et la formation.<\/p><p><strong>Mise en \u0153uvre et formation :<\/strong><br \/>La t\u00e2che la plus difficile pour le mus\u00e9e au cours du processus de mise en \u0153uvre a \u00e9t\u00e9 de fournir un fichier de donn\u00e9es propre \u00e0 importer, car il disposait de plusieurs installations FileMaker qui devaient \u00eatre combin\u00e9es. Une fois la base de donn\u00e9es op\u00e9rationnelle, Cividesk a assur\u00e9 une formation sur site en fran\u00e7ais par un \u00ab membre du personnel comp\u00e9tent \u00bb, essentielle pour un bon d\u00e9marrage du syst\u00e8me. N\u00e9anmoins, ils ont encore eu besoin de plusieurs s\u00e9ances plus tard sur certains sujets pour mieux comprendre des fonctionnalit\u00e9s telles que la gestion des adh\u00e9sions, l&#039;exportation de donn\u00e9es et la cr\u00e9ation de rapports.<\/p><p><strong>Usage quotidien:<\/strong><br \/>Le mus\u00e9e se concentre actuellement sur la gestion des adh\u00e9sions dans CiviCRM, \u00e0 la fois en enregistrant les nouvelles adh\u00e9sions et en envoyant des avis de renouvellement aux membres expir\u00e9s. La fonctionnalit\u00e9 de rappels de calendrier de CiviCRM facilite l&#039;envoi d&#039;e-mails automatis\u00e9s aux membres lorsque leur adh\u00e9sion est sur le point d&#039;expirer, ce qui est particuli\u00e8rement utile pour les adh\u00e9sions glissantes qui expirent \u00e0 diff\u00e9rents moments de l&#039;ann\u00e9e. Le fait que tous les dons soient enregistr\u00e9s au m\u00eame endroit dans la fiche de contact constitue un autre avantage consid\u00e9rable pour le mus\u00e9e. \u00ab Nous avons un d\u00e9veloppement personnalis\u00e9 dans CiviCRM o\u00f9 il y a une s\u00e9paration automatique du paiement entre la cotisation et le don. Nous proposons une cat\u00e9gorie d&#039;adh\u00e9sion o\u00f9 vous pouvez devenir membre et faire en m\u00eame temps un don d\u00e9ductible d&#039;imp\u00f4t. Le d\u00e9veloppement personnalis\u00e9 divise automatiquement la contribution afin qu&#039;une partie soit enregistr\u00e9e comme paiement d&#039;adh\u00e9sion et l&#039;autre comme don. Il s&#039;agit d&#039;un d\u00e9veloppement r\u00e9cent<br \/>que Cividesk a cr\u00e9\u00e9 pour nous \u00bb explique Louise.<br \/>Un autre d\u00e9veloppement personnalis\u00e9 cr\u00e9\u00e9 par Cividesk est une option de recherche sp\u00e9ciale o\u00f9 une liste de villes fran\u00e7aises appara\u00eet une fois qu&#039;un code postal est saisi. Les contacts peuvent choisir le nom de leur ville dans cette liste, ce qui augmente l&#039;efficacit\u00e9 lors du remplissage d&#039;un formulaire en ligne et a permis d&#039;am\u00e9liorer la normalisation des noms de villes dans la base de donn\u00e9es. Ceci est particuli\u00e8rement utile en fran\u00e7ais o\u00f9 il y a diff\u00e9rents accents et diff\u00e9rentes majuscules dans les noms propres. <br \/>Le personnel utilise \u00e9galement CiviMail pour envoyer des e-mails en masse aux contacts, effectuer des recherches et exporter des donn\u00e9es, autant de fonctionnalit\u00e9s CiviCRM qui facilitent leurs op\u00e9rations quotidiennes.<br \/>Cividesk fournit un support technique et un mentorat dans le cadre de l&#039;abonnement mensuel et S\u00e9bastien a \u00e9t\u00e9 tr\u00e8s satisfait des r\u00e9ponses aux questions.<br \/>\u00ab Lorsque j&#039;envoie un e-mail au support, j&#039;obtiens g\u00e9n\u00e9ralement une r\u00e9ponse rapide, malgr\u00e9 le d\u00e9calage horaire, car Cividesk dispose d&#039;un personnel d&#039;assistance travaillant dans diff\u00e9rents fuseaux horaires, ce qui augmente sa disponibilit\u00e9 pour les clients du monde entier \u00bb, a ajout\u00e9 S\u00e9bastien.<\/p><p><strong>Conseils pour les autres organisations envisageant CiviCRM\u00a0:<\/strong><br \/>S\u00e9bastien recommande de prendre suffisamment de temps pour pr\u00e9parer les fichiers \u00e0 importer et de parcourir les donn\u00e9es existantes pour nettoyer les doublons. Une fois CiviCRM mis en place, \u00ab Il est important de mettre en place des proc\u00e9dures avec le personnel pour que tout le monde utilise la base de donn\u00e9es de la m\u00eame mani\u00e8re et saisisse les donn\u00e9es dans un format standardis\u00e9, sinon cela devient un probl\u00e8me o\u00f9 vous n&#039;avez pas de coh\u00e9rence avec les majuscules et les accents \u00bb.<br \/><br \/><strong>Projets d&#039;avenir :<\/strong><br \/>Le mus\u00e9e travaille \u00e0 l&#039;\u00e9laboration d&#039;une proc\u00e9dure permettant de garantir le respect de la r\u00e9glementation europ\u00e9enne sur la protection des donn\u00e9es (RGPD). Pour le moment, ils se concentrent sur l\u2019utilisation quotidienne de CiviCRM pour les aider \u00e0 accomplir plus efficacement les op\u00e9rations globales du mus\u00e9e. \u00ab Le soutien continu de Cividesk avec sa r\u00e9ponse rapide aux probl\u00e8mes ou aux questions qui se posent fait partie int\u00e9grante de cette \u00e9quation. \u00bb<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>The Mus\u00e9e d&#8217;Art et d&#8217;Histoire du Juda\u00efsme (mahJ) is the largest French museum of Jewish art and history. Located in the Marais district of Paris, France, the museum\u2019s permanent collection presents 700 works of art and objects out of the 12,000 objects in its collection, that represent the history of Jewish communities in Europe and [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1656,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-success-story"],"_links":{"self":[{"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/posts\/1633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/comments?post=1633"}],"version-history":[{"count":20,"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/posts\/1633\/revisions"}],"predecessor-version":[{"id":1655,"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/posts\/1633\/revisions\/1655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/media\/1656"}],"wp:attachment":[{"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/media?parent=1633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/categories?post=1633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cividesk.com\/fr\/wp-json\/wp\/v2\/tags?post=1633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}